

{"id":43748,"date":"2021-04-29T15:46:46","date_gmt":"2021-04-29T13:46:46","guid":{"rendered":"https:\/\/eu.questionpro.de\/?p=32671"},"modified":"2021-04-29T15:46:46","modified_gmt":"2021-04-29T13:46:46","slug":"umfrage-sms-versenden","status":"publish","type":"post","link":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/","title":{"rendered":"Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 mit QuestionPro"},"content":{"rendered":"\n\n\n<\/p>\n<div class=\"blogcatmobile\"><\/div>\n<p><span class=\"blogcat\">Tipps &amp; Best Practices<\/span><\/p>\n<h1 style=\"color: #3f4a65; font-size: 35px; margin-top: 10px;\">SMS Umfrage: Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 Wir zeigen Ihnen, wie einfach das it QuestionPro geht.<\/h1>\n<p>\n<p><\/p>\n<p><\/p>\n\n<br \/>\n&#8211;<br \/>\n\n<p><\/p>\n<\/p>\n<div class=\"blogadvert\">Testen Sie die Vollversion von QuestionPro jetzt 10 Tage kostenlos<\/div>\n<div class=\"advertbullet\">KEINE KREDITKARTE NOTWENDIG. KEINE AUTOMATISCHE UMWANDLUNG IN EINE BEZAHL-LIZENZ.<\/div>\n<div style=\"margin-bottom: 10%;\"><\/div>\n<p style=\"text-align: center;\"><a style=\"letter-spacing: 0.15em; font-size: 17px; color: #ffffff; text-decoration: none; line-height: 1.5; background-color: #ec4d14; padding: 10px 19px 10px 19px; border-radius: 6px;\" title=\"Kostenlos Umfrage erstellen\" href=\"https:\/\/eu.questionpro.com\/a\/showEntry.do?lan=de_DEclassID=117&amp;sourceRef=group\">TESTEN<\/a><\/p>\n<p>\n<p><\/p>\n\n<\/p>\n<div style=\"margin-top: -15px;\"><\/div>\n<p><span class=\"shortdescription\">Insbesondere bei kleinen Umfragen sollten Sie den Versand per SMS durchaus in Erw\u00e4gung ziehen. QuestionPro ist hierf\u00fcr das ideale Werkzeug.<\/span><br \/>\n\n\n<br \/>\n<br \/>\n\n\n<\/p>\n<h2>H\u00f6here \u00d6ffnungsraten und direktes Feedback bei SMS Umfragen<\/h2>\n<p>Es ist unter Marketingfachleuten hinl\u00e4nglich bekannt, dass die \u00d6ffnungsraten von SMS Nachrichten um ein Vielfaches\u00a0h\u00f6her sind als die von E-Mails. Daher entdecken viele Marktforscher das Medium SMS f\u00fcr Umfragen im Rahmen der\u00a0Mobilen Marktforschung derzeit wieder. Ganz gleich, ob es der Telefon- oder Internetanbieter, das Shopping-Portal oder aber die Fluglinie ist: es wird wieder vermehrt &#8222;gesimst&#8220;! Und zwar vor allem wenn es darum geht, Kunden danach zu fragen, wie zufrieden diese sind, werden SMS Umfragen gerne genutzt. Ein gro\u00dfer Vorteil der SMS ist, dass sie kaum noch im Alltag genutzt wird und somit wieder eine besondere Stellung genie\u00dft und somit auch mehr Aufmerksamkeit.<\/p>\n<h2>Die SMS ist bei Umfragen herrlich unverbraucht!<\/h2>\n<p>Die SMS scheint f\u00fcr viele junge Leute in Zeiten von Facebook und WhatsApp ein total antiquiertes Kommunikationsmedium zu sein &#8211; fast wie f\u00fcr die \u00e4ltere Generation das Fax. Nur noch wenige SMS erh\u00e4lt man heute, vielleicht noch von seinem Telefonanbieter. Ansonsten bleibt das SMS-Signal stumm. Doch das hat f\u00fcr Unternehmen, die Online Umfragen durchf\u00fchren, einen echten Vorteil: Die SMS ist nicht so verbraucht wie etwa das Medium E-Mail. Sie erhalten mit gro\u00dfer Wahrscheinlichkeit eine hohe Aufmerksamkeit, wenn Sie Ihre Online Umfrage per SMS versenden.<\/p>\n<h2>SMS Umfragen &#8211; Variante 1:<br \/>\nDirekte Befragung innerhalb der SMS<\/h2>\n<p>Eine Methode, seine Kunden per SMS zu befragen, ist, dieses direkt innerhalb der SMS zu tun. Dabei wird an den Kunden eine Kurznachricht geschickt, die in der Regel mit der Frage beginnt, ob der Kunde gerne an einer\u00a0Umfrage teilnehmen m\u00f6chte.<\/p>\n<blockquote><p>&#8222;Sie haben k\u00fcrzlich mit unserem Kundenservice telefoniert.<br \/>\nD\u00fcrfen wie Ihnen zur Verbesserung unseres Services drei kurze Fragen hierzu stellen?&#8220;<\/p><\/blockquote>\n<p>Die Antwortoptionen werden gleich mitgesendet: &#8222;Antworten Sie bitte mit Ja oder Nein\u201d. Bei einem Nein erh\u00e4lt der Kunde eine nette Dankes-Notiz. Wenn der Kunde gar nicht antwortet, so kann man nach einiger Zeit eine Erinnerungsnachricht versenden. Bei einem Ja wird automatisch die n\u00e4chste Frage durch die Befragungssoftware versendet, beispielsweise:<\/p>\n<blockquote><p>&#8222;Haben Sie das Telefonat mit unserem Service als freundlich empfunden?<br \/>\nBitte geben Sie ein J f\u00fcr Ja und ein N f\u00fcr Nein ein!&#8220;<\/p><\/blockquote>\n<p>Die Antwortm\u00f6glichkeiten\u00a0k\u00f6nnen hierbei selbstverst\u00e4ndlich\u00a0variabel gestaltet werden. Andere Unternehmen geben beispielsweise eine Benotung nach dem Schulnotensystem vor.<\/p>\n<blockquote><p>&#8222;Antworten Sie bitte nach dem Schulnotensystem,<br \/>\nwobei 1 die beste, 6 die schlechteste Note ist.\u201d<\/p><\/blockquote>\n<p>SMS Befragungen sollten kurz und knapp gehalten sein. Am besten, Sie erw\u00e4hnen bereits bei der Eingangs-SMS, wie viele Fragen der Kunde zu erwarten hat, so vermeiden Sie unn\u00f6tige Umfrageabbr\u00fcche und Frust auf Seiten Ihrer Kunden.<\/p>\n<p>Im \u00dcbrigen: Auch Freitextantworten sind bei SMS Befragungen denkbar. Denken Sie allerdings daran, dass nicht jeder gro\u00dfe Lust hat, viel Text mit der Smartphone-Tastatur zu tippen. Formulieren\u00a0Sie daher Ihre Fragen derart, dass diese mit sehr wenig Freitext beantworten werden k\u00f6nnen.<\/p>\n<h2>SMS Umfragen: Variante 2:<br \/>\nLink zu einem Online Fragebogen<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-11334 size-full\" title=\"SMS Umfrage durchf\u00fchren\" src=\"https:\/\/www.questionpro.de\/wp-content\/uploads\/2019\/08\/SMS-Umfrage.jpg\" alt=\"SMS Umfrage durchf\u00fchren\" width=\"300\" height=\"273\" \/>Eine andere Methode, die Unternehmen sehr gerne nutzen, ist schlicht und ergreifend der Versand eines Links per SMS, der auf eine Landing-Page zu einem Online-Fragebogen f\u00fchrt. Dieser Fragebogen sollte selbstverst\u00e4ndlich f\u00fcr die Anzeige auf einem mobilen Endger\u00e4t optimiert sein.\u00a0Ganz gleich, f\u00fcr welche Variante Sie sich entscheiden: Eine SMS als &#8222;Tr\u00e4germedium\u201d f\u00fcr Ihre Mobile Befragung erh\u00f6ht die Wahrscheinlichkeit, dass Ihr Anliegen deutlich mehr Beachtung findet. Denn das Medium SMS ist bei weitem nicht so sehr verbraucht wie die E-Mail.<\/p>\n<p>Aber Vorsicht: Ihre Kunden k\u00f6nnten es als aufdringlich empfinden, wenn Sie st\u00e4ndig irgendwelche SMS von Ihnen oder auch von anderen Unternehmen erhalten. Daher sollte der Versand einer SMS immer einen direkten Bezug zu einer vorausgegangenen Interaktion haben, etwa eine Bestellung\u00a0oder eine\u00a0Serviceanfrage. Werbung sollte\u00a0tabu sein. Das nervt nur!<\/p>\n<h2>Und so einfach versenden Sie mit QuestionPro Ihre Online Umfragen per SMS<\/h2>\n<p>Um SMS-Einladungen zu Online Umfragen mit QuestionPro an potentielle UmfrageteilnehmerInnen zu versenden, navigieren Sie in Ihrem Benutzerkonto zu: Umfragen \u2192 Distribution \u2192 E-Mail \u2192 Verfassen und stellen Sie den &#8222;SMS\u201d-Umschalter auf &#8222;Ein\u201d.<\/p>\n<p><a href=\"https:\/\/www.questionpro.de\/wp-content\/uploads\/2019\/08\/Umfrage-per-SMS-versenden.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"lightbox alignnone wp-image-11335 size-full\" title=\"Umfrage per SMS versenden\" src=\"https:\/\/www.questionpro.de\/wp-content\/uploads\/2019\/08\/Umfrage-per-SMS-versenden.jpg\" alt=\"Umfrage per SMS versenden\" width=\"800\" height=\"435\" \/><\/a><\/p>\n<hr \/>\n<p><em>WICHTIG: Diese Option steht Ihnen erst dann zur Verf\u00fcgung, wenn Sie zuvor sogenannte SMS Credits kaufen! Wenn Sie keine SMS Credits besitzen, dann sehen Sie an Stelle des SMS Umschalters einen Link zu einer Bestellmaske.<\/em><\/p>\n<p>W\u00e4hlen Sie die E-Mail-Liste aus, in die Sie die Kontakte und Telefonnummern hochgeladen haben oder erstellen Sie eine neue Kontaktliste. Sie k\u00f6nnen auch nachtr\u00e4glich Telefonnummern zu bestehen Kontaktlisten hinzuf\u00fcgen. Eine Anleitung zur Editierung bestehender Listen finden Sie auch auf unseren Hilfe Seiten. \u2192 <a href=\"https:\/\/www.questionpro.com\/de\/help\/514.html\" target=\"_blank\" rel=\"noopener noreferrer\">Umfrage per SMS versenden<\/a>.<\/p>\n<p><a href=\"https:\/\/www.questionpro.de\/wp-content\/uploads\/2019\/08\/SMS-Umfragen-versenden_1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"lightbox alignnone wp-image-11336 size-full\" title=\"SMS Umfrage\" src=\"https:\/\/www.questionpro.de\/wp-content\/uploads\/2019\/08\/SMS-Umfragen-versenden_1.jpg\" alt=\"SMS Umfrage\" width=\"800\" height=\"321\" \/><\/a><\/p>\n<hr \/>\n<p>W\u00e4hlen Sie anschlie\u00dfend die Vorlage f\u00fcr die SMS-Einladung aus und passen Sie die Nachricht nach belieben an und klicken Sie schlussendlich\u00a0auf &#8222;Senden\u201d. Das wars schon!<\/p>\n<p>Welche M\u00f6glichkeit Sie noch haben, um Ihre Online-Umfragen zu verteilen, haben wie f\u00fcr Sie in dem Blogartikel zusammengefasst: \u00a0\u2192 <a href=\"https:\/\/www.questionpro.de\/online-umfrage-verteilen-veroeffentlichen\/\" target=\"_blank\" rel=\"noopener noreferrer\">&#8222;So verteilen Sie Ihre Online Umfragen und Erhebungen effizient und schnell mit QuestionPro&#8220;<\/a>.<\/p>\n<h2>Entstehen Kosten f\u00fcr den<br \/>\nVersand von SMS-Nachrichten?<\/h2>\n<p>Wie bei jeder SMS gelten auch hier die \u00fcblichen SMS-Tarife. QuestionPro bietet Ihnen eine SMS-Guthabenoption, mit der Sie alle anfallenden Kosten decken k\u00f6nnen.<br \/>\n\n\n<\/p>\n<h2><span style=\"line-heigh: 1.5; color: #e65c00;\">1:1 Live-Online-Demo:<\/span><br \/>\nUmfragen per SMS versenden mit der Umfrage Software QuestionPro<\/h2>\n<p>Sie m\u00f6chten mehr \u00fcber QuestionPro erfahren und wie man mit der beliebten Umfrage Software Umfragen per SMS versendet? Sehr gerne zeigen wir Ihnen in einer pers\u00f6nlichen 1:1 Live-Online-Demo Features und Fragetypen der Umfrage-Software QuestionPro. Vereinbaren Sie jetzt einen individuellen Termin.<br \/>\n\n<br \/>\n<br \/>\n<br \/>\n<br \/>\n<br \/>\n<br \/>\n<br \/>\n\n<\/p>\n<hr \/>\n<h2 style=\"margin-bottom: 35px;\">Kostenlos Umfragen erstellen mit der professionellen und webbasierten Umfrage-Software QuestionPro<\/h2>\n<p>Sie haben Fragen oder Anregungen?\u00a0Wir freuen uns sehr auf Ihre Anfrage! <a title=\"QuestionPro Kontaktformular\" href=\"https:\/\/www.questionpro.de\/kontakt\/\">Nutzen Sie hierzu ganz einfach das Kontaktformular<\/a>. Registrieren Sie sich jetzt kostenlos und erstellen Sie Ihre erste Online-Umfrage mit QuestionPro.<br \/>\n\n<\/p>\n<div style=\"background-color: #80c6f0; padding-top: 15px; padding-bottom: 25px; background-image: url('https:\/\/www.questionpro.de\/wp-content\/uploads\/2021\/03\/Kostenlose-Umfrage-Software-Banner.jpg'); background-repeat: no-repeat; background-position: left center;\">\n<div class=\"blogbody\">\n<p style=\"text-align: center; padding-left: 5%; padding-right: 5%;\"><span class=\"bottomad\">WIR SCHENKEN IHNEN 300 FEEDBACKS PRO UMFRAGE. ERSTELLEN SIE SO VIELE UMFRAGEN WIE SIE M\u00d6CHTEN!<\/span><\/p>\n<\/div>\n<div style=\"margin-bottom: 5%;\"><\/div>\n<p style=\"text-align: center;\"><a style=\"letter-spacing: 0.15em; font-size: 17px; color: #ffffff; text-decoration: none; line-height: 1.5; background-color: #ec4d14; padding: 10px 19px 10px 19px; border-radius: 6px;\" title=\"Jetzt kostenlos Umfrage Software testen\" href=\"https:\/\/eu.questionpro.com\/a\/showEntry.do?lan=de_DE\"><span style=\"font-size: 12pt;\">KOSTENLOS TESTEN!<\/span><\/a><\/p>\n<\/div>\n<p>\n<\/p>\n<hr \/>\n<p style=\"font-weight: 600; margin-bottom: 5px;\">WEITERF\u00dcHRENDE STICHWORTE<\/p>\n<p><span class=\"blogtags\">Umfrage-Software | Umfrage versenden | Umfrageteilnehmer | Funktionen\u00a0<\/span><br \/>\n\n\n<br \/>\n<span style=\"font-weight: 600;\">DIESEN ARTIKEL TEILEN<\/span><\/p>\n<p><br \/>\n\n<\/p>\n<hr \/>\n<p style=\"font-weight: 600; margin-bottom: 5px;\">STICHW\u00d6RTER DIESES BLOG-BEITRAGS<\/p>\n<p><span class=\"blogkeywords\"><strong>SMS<\/strong> | <strong>Umfrage<\/strong> | <strong>versenden<\/strong> | <strong>verteilen<\/strong> | <strong>\u00d6ffnungsrate<\/strong><\/span><br \/>\n\n<p><\/p>\n\n<\/p>\n<ul>\n<li><a title=\"Mehrsprachige Umfragen erstellen\" href=\"https:\/\/www.questionpro.de\/online-umfrage-mehrsprachig-erstellen\/\">Mehrsprachige Umfragen<\/a><\/li>\n<li><a title=\"Top Features und Funktionen\" href=\"https:\/\/www.questionpro.de\/umfrage-durchfuehren-software-tool\/\">Top Features und Funktionen<\/a><\/li>\n<li><a title=\"Fragebogen im Chat Stil\" href=\"https:\/\/www.questionpro.de\/chat-fragebogen\/\">Chat-Fragebogen<\/a><\/li>\n<li><a title=\"Fragebogen erstellen. Aufbau, Layout, Tipps.\" href=\"https:\/\/www.questionpro.de\/fragebogen-erstellen-aufbau\/\">Fragebogen erstellen<\/a><\/li>\n<li><a title=\"Feedback steigern bei Online Umfragen\" href=\"https:\/\/www.questionpro.de\/umfrage-feedback-steigern-tipps\/\">Umfrage-Feedback steigern<\/a><\/li>\n<\/ul>\n<p>\n\n\n\n\n\n\n<p><br \/>\n<\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p><\/p>\n\n<p><br \/>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.<\/p>\n","protected":false},"author":192,"featured_media":43686,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_focuskw":"SMS-Umfrage","_yoast_wpseo_title":"SMS-Umfrage versenden, durchf\u00fchren & auswerten - QuestionPro","_yoast_wpseo_metadesc":"Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.","_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[2585],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SMS-Umfrage versenden, durchf\u00fchren &amp; auswerten - QuestionPro<\/title>\n<meta name=\"description\" content=\"Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Umfrage per SMS versenden und durchf\u00fchren - QuestionPro\" \/>\n<meta property=\"og:description\" content=\"Eine SMS Umfrage versenden Sie schnell und einfach mit QuestionPro, eines der weiltweit meist genutzten Umfrage Tools. Jetzt 14 Tage testen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\" \/>\n<meta property=\"og:site_name\" content=\"QuestionPro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/questionpro\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-29T13:46:46+00:00\" \/>\n<meta name=\"author\" content=\"Thomas Maiwald\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Umfrage per SMS versenden und durchf\u00fchren - QuestionPro\" \/>\n<meta name=\"twitter:description\" content=\"Eine SMS Umfrage versenden Sie schnell und einfach mit QuestionPro, eines der weiltweit meist genutzten Umfrage Tools. Jetzt 14 Tage testen.\" \/>\n<meta name=\"twitter:creator\" content=\"@questionpro\" \/>\n<meta name=\"twitter:site\" content=\"@questionpro\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Thomas Maiwald\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\"},\"author\":{\"name\":\"Thomas Maiwald\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/e6c11b8d078203dd32a8c118f41a40e7\"},\"headline\":\"Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 mit QuestionPro\",\"datePublished\":\"2021-04-29T13:46:46+00:00\",\"dateModified\":\"2021-04-29T13:46:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\"},\"wordCount\":3561,\"publisher\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#organization\"},\"articleSection\":[\"Blog\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\",\"url\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\",\"name\":\"SMS-Umfrage versenden, durchf\u00fchren & auswerten - QuestionPro\",\"isPartOf\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#website\"},\"datePublished\":\"2021-04-29T13:46:46+00:00\",\"dateModified\":\"2021-04-29T13:46:46+00:00\",\"description\":\"Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.questionpro.com\/blog\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Unkategorisiert\",\"item\":\"https:\/\/www.questionpro.com\/blog\/de\/category\/unkategorisiert\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 mit QuestionPro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#website\",\"url\":\"https:\/\/www.questionpro.com\/blog\/de\/\",\"name\":\"QuestionPro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.questionpro.com\/blog\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#organization\",\"name\":\"QuestionPro\",\"url\":\"https:\/\/www.questionpro.com\/blog\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.questionpro.com\/blog\/wp-content\/uploads\/2022\/10\/questionpro-logo.svg\",\"contentUrl\":\"https:\/\/www.questionpro.com\/blog\/wp-content\/uploads\/2022\/10\/questionpro-logo.svg\",\"caption\":\"QuestionPro\"},\"image\":{\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/questionpro\",\"https:\/\/twitter.com\/questionpro\",\"https:\/\/www.linkedin.com\/company\/questionpro\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/e6c11b8d078203dd32a8c118f41a40e7\",\"name\":\"Thomas Maiwald\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/37338890814892c0b074968d390ae948?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/37338890814892c0b074968d390ae948?s=96&d=mm&r=g\",\"caption\":\"Thomas Maiwald\"},\"description\":\"Managing Director der QuestionPro GmbH, einem f\u00fchrenden Softwareanbieter f\u00fcr Customer Experience, Marktforschung und Employee Experience.\",\"sameAs\":[\"https:\/\/www.questionpro.de\/\"],\"url\":\"https:\/\/www.questionpro.com\/blog\/de\/author\/thomas-maiwald-immer\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SMS-Umfrage versenden, durchf\u00fchren & auswerten - QuestionPro","description":"Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/","og_locale":"de_DE","og_type":"article","og_title":"Umfrage per SMS versenden und durchf\u00fchren - QuestionPro","og_description":"Eine SMS Umfrage versenden Sie schnell und einfach mit QuestionPro, eines der weiltweit meist genutzten Umfrage Tools. Jetzt 14 Tage testen.","og_url":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/","og_site_name":"QuestionPro","article_publisher":"https:\/\/www.facebook.com\/questionpro","article_published_time":"2021-04-29T13:46:46+00:00","author":"Thomas Maiwald","twitter_card":"summary_large_image","twitter_title":"Umfrage per SMS versenden und durchf\u00fchren - QuestionPro","twitter_description":"Eine SMS Umfrage versenden Sie schnell und einfach mit QuestionPro, eines der weiltweit meist genutzten Umfrage Tools. Jetzt 14 Tage testen.","twitter_creator":"@questionpro","twitter_site":"@questionpro","twitter_misc":{"Verfasst von":"Thomas Maiwald","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#article","isPartOf":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/"},"author":{"name":"Thomas Maiwald","@id":"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/e6c11b8d078203dd32a8c118f41a40e7"},"headline":"Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 mit QuestionPro","datePublished":"2021-04-29T13:46:46+00:00","dateModified":"2021-04-29T13:46:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/"},"wordCount":3561,"publisher":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/#organization"},"articleSection":["Blog"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/","url":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/","name":"SMS-Umfrage versenden, durchf\u00fchren & auswerten - QuestionPro","isPartOf":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/#website"},"datePublished":"2021-04-29T13:46:46+00:00","dateModified":"2021-04-29T13:46:46+00:00","description":"Eine SMS-Umfrage erstellen und versenden Sie schnell und einfach mit QuestionPro, eines der weltweit meist genutzten Umfrage-Tools.","breadcrumb":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.questionpro.com\/blog\/de\/umfrage-sms-versenden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.questionpro.com\/blog\/de\/"},{"@type":"ListItem","position":2,"name":"Unkategorisiert","item":"https:\/\/www.questionpro.com\/blog\/de\/category\/unkategorisiert\/"},{"@type":"ListItem","position":3,"name":"Versenden Sie Ihre Umfrage doch auch mal per SMS \u2013 mit QuestionPro"}]},{"@type":"WebSite","@id":"https:\/\/www.questionpro.com\/blog\/de\/#website","url":"https:\/\/www.questionpro.com\/blog\/de\/","name":"QuestionPro","description":"","publisher":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.questionpro.com\/blog\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.questionpro.com\/blog\/de\/#organization","name":"QuestionPro","url":"https:\/\/www.questionpro.com\/blog\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/logo\/image\/","url":"https:\/\/www.questionpro.com\/blog\/wp-content\/uploads\/2022\/10\/questionpro-logo.svg","contentUrl":"https:\/\/www.questionpro.com\/blog\/wp-content\/uploads\/2022\/10\/questionpro-logo.svg","caption":"QuestionPro"},"image":{"@id":"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/questionpro","https:\/\/twitter.com\/questionpro","https:\/\/www.linkedin.com\/company\/questionpro\/"]},{"@type":"Person","@id":"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/e6c11b8d078203dd32a8c118f41a40e7","name":"Thomas Maiwald","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.questionpro.com\/blog\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/37338890814892c0b074968d390ae948?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/37338890814892c0b074968d390ae948?s=96&d=mm&r=g","caption":"Thomas Maiwald"},"description":"Managing Director der QuestionPro GmbH, einem f\u00fchrenden Softwareanbieter f\u00fcr Customer Experience, Marktforschung und Employee Experience.","sameAs":["https:\/\/www.questionpro.de\/"],"url":"https:\/\/www.questionpro.com\/blog\/de\/author\/thomas-maiwald-immer\/"}]}},"featured_image_src":null,"featured_image_src_square":null,"author_info":{"display_name":"Thomas Maiwald","author_link":"https:\/\/www.questionpro.com\/blog\/de\/author\/thomas-maiwald-immer\/"},"_links":{"self":[{"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/posts\/43748"}],"collection":[{"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/users\/192"}],"replies":[{"embeddable":true,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/comments?post=43748"}],"version-history":[{"count":0,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/posts\/43748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/media?parent=43748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/categories?post=43748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.questionpro.com\/blog\/de\/wp-json\/wp\/v2\/tags?post=43748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}